{"id":3507,"date":"2022-10-25T11:06:00","date_gmt":"2022-10-25T11:06:00","guid":{"rendered":"https:\/\/www.kestersearch.com\/insights-and-events\/?p=3507"},"modified":"2022-10-23T23:13:06","modified_gmt":"2022-10-23T23:13:06","slug":"forget-about-goal-setting-try-these-5-strategies-instead","status":"publish","type":"post","link":"https:\/\/www.kestersearch.com\/insights-and-events\/news\/2022\/10\/forget-about-goal-setting-try-these-5-strategies-instead\/","title":{"rendered":"Forget about goal setting. Try these 5 strategies instead"},"content":{"rendered":"\n<p>Here are five ways to take charge of your career and successfully meet your <a href=\"https:\/\/www.fastcompany.com\/90795572\/forget-about-goal-setting-try-these-5-strategies-instead?partner=rss&amp;utm_source=rss&amp;utm_medium=feed&amp;utm_campaign=rss+fastcompany&amp;utm_content=rss\" title=\"\">goals:<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Here are five ways to take charge of your career and successfully meet your goals:<\/p>\n","protected":false},"author":13,"featured_media":3508,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[14,11,10],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.kestersearch.com\/insights-and-events\/wp-json\/wp\/v2\/posts\/3507"}],"collection":[{"href":"https:\/\/www.kestersearch.com\/insights-and-events\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kestersearch.com\/insights-and-events\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kestersearch.com\/insights-and-events\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kestersearch.com\/insights-and-events\/wp-json\/wp\/v2\/comments?post=3507"}],"version-history":[{"count":1,"href":"https:\/\/www.kestersearch.com\/insights-and-events\/wp-json\/wp\/v2\/posts\/3507\/revisions"}],"predecessor-version":[{"id":3509,"href":"https:\/\/www.kestersearch.com\/insights-and-events\/wp-json\/wp\/v2\/posts\/3507\/revisions\/3509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kestersearch.com\/insights-and-events\/wp-json\/wp\/v2\/media\/3508"}],"wp:attachment":[{"href":"https:\/\/www.kestersearch.com\/insights-and-events\/wp-json\/wp\/v2\/media?parent=3507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kestersearch.com\/insights-and-events\/wp-json\/wp\/v2\/categories?post=3507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kestersearch.com\/insights-and-events\/wp-json\/wp\/v2\/tags?post=3507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}